{"id":6913,"date":"2025-10-30T09:20:20","date_gmt":"2025-10-30T08:20:20","guid":{"rendered":"https:\/\/www.kks-aachen.de\/?p=6913"},"modified":"2025-10-30T09:44:32","modified_gmt":"2025-10-30T08:44:32","slug":"debattierprojekt-in-der-euregio","status":"publish","type":"post","link":"https:\/\/www.kks-aachen.de\/fr\/debattierprojekt-in-der-euregio\/","title":{"rendered":"Debattierprojekt in der Euregio"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":6918,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_searchwp_excluded":"","inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Debattierprojekt in der Euregio - KKS Aachen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kks-aachen.de\/fr\/debattierprojekt-in-der-euregio\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Debattierprojekt in der Euregio - KKS Aachen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kks-aachen.de\/fr\/debattierprojekt-in-der-euregio\/\" \/>\n<meta property=\"og:site_name\" content=\"KKS Aachen\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-30T08:20:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T08:44:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kks-aachen.de\/app\/uploads\/2025\/10\/debattier1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"738\" \/>\n\t<meta property=\"og:image:height\" content=\"416\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Conny Hanterman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Conny Hanterman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kks-aachen.de\/fr\/debattierprojekt-in-der-euregio\/\",\"url\":\"https:\/\/www.kks-aachen.de\/fr\/debattierprojekt-in-der-euregio\/\",\"name\":\"Debattierprojekt in der Euregio - KKS Aachen\",\"isPartOf\":{\"@id\":\"https:\/\/www.kks-aachen.de\/fr\/#website\"},\"datePublished\":\"2025-10-30T08:20:20+00:00\",\"dateModified\":\"2025-10-30T08:44:32+00:00\",\"author\":{\"@id\":\"https:\/\/www.kks-aachen.de\/fr\/#\/schema\/person\/08a104a047067d51186c3d1d5432047c\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kks-aachen.de\/fr\/debattierprojekt-in-der-euregio\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kks-aachen.de\/fr\/#website\",\"url\":\"https:\/\/www.kks-aachen.de\/fr\/\",\"name\":\"KKS Aachen\",\"description\":\"Wir. Leben. Schule.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kks-aachen.de\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.kks-aachen.de\/fr\/#\/schema\/person\/08a104a047067d51186c3d1d5432047c\",\"name\":\"Conny Hanterman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.kks-aachen.de\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/be1c249a775c3ae7b57b1970e701cd1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/be1c249a775c3ae7b57b1970e701cd1a?s=96&d=mm&r=g\",\"caption\":\"Conny Hanterman\"},\"url\":\"https:\/\/www.kks-aachen.de\/fr\/author\/connyhanterman\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Debattierprojekt in der Euregio - KKS Aachen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kks-aachen.de\/fr\/debattierprojekt-in-der-euregio\/","og_locale":"fr_FR","og_type":"article","og_title":"Debattierprojekt in der Euregio - KKS Aachen","og_url":"https:\/\/www.kks-aachen.de\/fr\/debattierprojekt-in-der-euregio\/","og_site_name":"KKS Aachen","article_published_time":"2025-10-30T08:20:20+00:00","article_modified_time":"2025-10-30T08:44:32+00:00","og_image":[{"width":738,"height":416,"url":"https:\/\/www.kks-aachen.de\/app\/uploads\/2025\/10\/debattier1.jpg","type":"image\/jpeg"}],"author":"Conny Hanterman","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Conny Hanterman","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kks-aachen.de\/fr\/debattierprojekt-in-der-euregio\/","url":"https:\/\/www.kks-aachen.de\/fr\/debattierprojekt-in-der-euregio\/","name":"Debattierprojekt in der Euregio - KKS Aachen","isPartOf":{"@id":"https:\/\/www.kks-aachen.de\/fr\/#website"},"datePublished":"2025-10-30T08:20:20+00:00","dateModified":"2025-10-30T08:44:32+00:00","author":{"@id":"https:\/\/www.kks-aachen.de\/fr\/#\/schema\/person\/08a104a047067d51186c3d1d5432047c"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kks-aachen.de\/fr\/debattierprojekt-in-der-euregio\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.kks-aachen.de\/fr\/#website","url":"https:\/\/www.kks-aachen.de\/fr\/","name":"KKS Aachen","description":"Wir. Leben. Schule.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kks-aachen.de\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.kks-aachen.de\/fr\/#\/schema\/person\/08a104a047067d51186c3d1d5432047c","name":"Conny Hanterman","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.kks-aachen.de\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/be1c249a775c3ae7b57b1970e701cd1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be1c249a775c3ae7b57b1970e701cd1a?s=96&d=mm&r=g","caption":"Conny Hanterman"},"url":"https:\/\/www.kks-aachen.de\/fr\/author\/connyhanterman\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 16:42:33","action":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/www.kks-aachen.de\/fr\/wp-json\/wp\/v2\/posts\/6913"}],"collection":[{"href":"https:\/\/www.kks-aachen.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kks-aachen.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kks-aachen.de\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kks-aachen.de\/fr\/wp-json\/wp\/v2\/comments?post=6913"}],"version-history":[{"count":13,"href":"https:\/\/www.kks-aachen.de\/fr\/wp-json\/wp\/v2\/posts\/6913\/revisions"}],"predecessor-version":[{"id":6956,"href":"https:\/\/www.kks-aachen.de\/fr\/wp-json\/wp\/v2\/posts\/6913\/revisions\/6956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kks-aachen.de\/fr\/wp-json\/wp\/v2\/media\/6918"}],"wp:attachment":[{"href":"https:\/\/www.kks-aachen.de\/fr\/wp-json\/wp\/v2\/media?parent=6913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kks-aachen.de\/fr\/wp-json\/wp\/v2\/categories?post=6913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kks-aachen.de\/fr\/wp-json\/wp\/v2\/tags?post=6913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}